{"id":960,"date":"2012-10-22T13:41:51","date_gmt":"2012-10-22T11:41:51","guid":{"rendered":"https:\/\/archives.courbevoie-rugby.com\/index.php\/2012\/10\/22\/courbevoie-seul-leader\/"},"modified":"2024-10-01T18:27:07","modified_gmt":"2024-10-01T16:27:07","slug":"courbevoie-seul-leader","status":"publish","type":"post","link":"https:\/\/archives.courbevoie-rugby.com\/index.php\/courbevoie-seul-leader\/","title":{"rendered":"Courbevoie seul leader !"},"content":{"rendered":"<p><span style=\"font-size: small; font-family: arial, helvetica, sans-serif;\">Grace \u00e0 sa victoire bonifi\u00e9e 28-13 \u00e0 Vincennes, Courbevoie est maintenant seul leader de la poule, suivi de pr\u00e8s par Domont et Antony eux aussi invaincus. Derri\u00e8re ces 3 \u00e9quipes le trou est fait. Les r\u00e9sultats complets de cette 5e journ\u00e9e :\u00a0<a href=\"index.php?option=com_joomleague&amp;func=showResultsRank&amp;p=31&amp;Itemid=70\">http:\/\/www.courbevoie-rugby.com\/index.php?option=com_joomleague&amp;func=showResultsRank&amp;p=31&amp;Itemid=70<\/a><\/span><\/p>\n<p><span style=\"font-size: small; font-family: arial, helvetica, sans-serif;\">De son c\u00f4t\u00e9 l&rsquo;\u00e9quipe reserve l&rsquo;a emport\u00e9 sur le score de 15 \u00e0 3<\/span><\/p>\n<p><span style=\"font-size: small; font-family: arial, helvetica, sans-serif;\">Dimanche prochain r\u00e9ception d&rsquo;epernay \u00e0 JP Rives tandis que Domont et Antony s&rsquo;affrontent.<\/span><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grace \u00e0 sa victoire bonifi\u00e9e 28-13 \u00e0 Vincennes, Courbevoie est maintenant seul leader de la poule, suivi de pr\u00e8s par Domont et Antony eux aussi invaincus. Derri\u00e8re ces 3 \u00e9quipes le trou est fait. Les r\u00e9sultats complets de cette 5e journ\u00e9e :\u00a0http:\/\/www.courbevoie-rugby.com\/index.php?option=com_joomleague&amp;func=showResultsRank&amp;p=31&amp;Itemid=70 De son c\u00f4t\u00e9 l&rsquo;\u00e9quipe reserve l&rsquo;a emport\u00e9 sur le score de 15 \u00e0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[82,2],"tags":[],"class_list":["post-960","post","type-post","status-publish","format-standard","hentry","category-archives","category-seniors"],"_links":{"self":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/comments?post=960"}],"version-history":[{"count":0,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/960\/revisions"}],"wp:attachment":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/media?parent=960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/categories?post=960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/tags?post=960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}