{"id":2867,"date":"2019-01-20T22:43:05","date_gmt":"2019-01-20T21:43:05","guid":{"rendered":"https:\/\/archives.courbevoie-rugby.com\/index.php\/2019\/01\/20\/fed3-sans-trembler-face-a-sucy\/"},"modified":"2024-10-01T18:21:21","modified_gmt":"2024-10-01T16:21:21","slug":"fed3-sans-trembler-face-a-sucy","status":"publish","type":"post","link":"https:\/\/archives.courbevoie-rugby.com\/index.php\/fed3-sans-trembler-face-a-sucy\/","title":{"rendered":"Fed3: sans trembler face \u00e0 Sucy"},"content":{"rendered":"<p><img decoding=\"async\" class=\" size-full wp-image-2864\" src=\"https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-9167.jpg\" alt=\"Loic-9167.jpg\" width=\"80%\" height=\"NaN\" style=\"display: block; margin-left: auto; margin-right: auto;\" srcset=\"https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-9167.jpg 1000w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-9167-300x200.jpg 300w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-9167-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Temps hivernal, terrain hivernal&#8230;.rugby hivernal. Il ne manquait que la pluie ou la neige pour que la tableau soit complet pour ce match retour face \u00e0 Sucy qui avait poser des probl\u00e8mes \u00e0 Courbevoie lors du match aller qui s\u00a0\u00bb\u00e9tait deroul\u00e9 dans des condition automnales&#8230;mais surtout apocalyptiques.<\/p>\n<p>&nbsp;<\/p>\n<p>L&rsquo;\u00e9quipe Une a su adapter son jeu \u00e0 l\u00a0\u00bb\u00e9tat du terrain, en sachant parfaitement alterner le jeu mettant tr\u00e8s souvent les visiteurs \u00e0 la faute. Les l\u00e9vriers ont su concr\u00e9tiser leur domination sur des p\u00e9naltouches et des m\u00eal\u00e9es proches de la ligne d&rsquo;enbut adverse. Si Courbevoie n&rsquo;a jamais \u00e9t\u00e9 mis en danger et semblait dominer son sujet, le score n&rsquo;\u00e9tait que de 10 \u00e0 3 juste avant le retour aux vestiaires, mais un essai \u00e0 la 40e donnait une plus large avance (17-3) \u00e0 Courbevoie.<\/p>\n<p>Avec le vent favorable, l&rsquo;apport du banc, Courbevoie prendra le large en seconde p\u00e9riode pour finalement s&rsquo;imposer sur le score de 38 \u00e0 3.&nbsp;<\/p>\n<p>De sonc c\u00f4t\u00e9, St-Denis s&rsquo;est impos\u00e9 facilement face \u00e0 l&rsquo;ACBB.<\/p>\n<p>Match plus compliqu\u00e9 pour la B qui a peut-\u00eatre montr\u00e9 \u00e0 la premi\u00e8re ce qu&rsquo;il ne fallait pas faire (3 cartons!). Men\u00e9s 12-0 apr\u00e8s une heure de jeu, Courbevoie a su arrach\u00e9 une victoire en inscrivant 3 essais en fin de match, la qualit\u00e9 et la jeunesse du banc a \u00e9t\u00e9 d\u00e9cisive face \u00e0 une \u00e9quipe qui pensait avoir fait le plus dur en menant au score pendant une heures face \u00e0 une \u00e9quipe invaincue en match de poule depuis un an et demi !<\/p>\n<p>Et puis le rugby est pass\u00e9 au second plan, quelque minutes entre les deux matchs, sur ce terrain boueux, au bord duquel Lo\u00efc s&rsquo;est ecroul\u00e9 il y a maintenant 6 ans (&nbsp;<a href=\"https:\/\/archives.courbevoie-rugby.com\/index.php\/2013\/01\/24\/le-rc-courbevoie-en-deuil\/\">Le RC Courbevoie en deuil<\/a>&nbsp;). Sa famille, ses proches et son club avaient tenu \u00e0 lui rendre hommage avec un lacher de ballons et une minute d&rsquo;applaudissements avant l&rsquo;entr\u00e9e des deux \u00e9quipes sur le terrain. Pour ne pas oublier que Lo\u00efc aurait maintenant 21 ans, qu&rsquo;il aurait peut-\u00eatre jou\u00e9 dans cette boue par ce froid dimanche de janvier.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\" size-full wp-image-2865\" src=\"https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-8689.jpg\" alt=\"Loic-8689.jpg\" width=\"80%\" height=\"NaN\" style=\"display: block; margin-left: auto; margin-right: auto;\" srcset=\"https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-8689.jpg 1600w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-8689-300x200.jpg 300w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-8689-1024x683.jpg 1024w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-8689-768x512.jpg 768w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-8689-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\" size-full wp-image-2866\" src=\"https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-8712.jpg\" alt=\"Loic-8712.jpg\" width=\"80%\" height=\"NaN\" style=\"display: block; margin-left: auto; margin-right: auto;\" srcset=\"https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-8712.jpg 1600w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-8712-300x200.jpg 300w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-8712-1024x683.jpg 1024w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-8712-768x512.jpg 768w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/Loic-8712-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Temps hivernal, terrain hivernal&#8230;.rugby hivernal. Il ne manquait que la pluie ou la neige pour que la tableau soit complet pour ce match retour face \u00e0 Sucy qui avait poser des probl\u00e8mes \u00e0 Courbevoie lors du match aller qui s\u00a0\u00bb\u00e9tait deroul\u00e9 dans des condition automnales&#8230;mais surtout apocalyptiques. &nbsp; L&rsquo;\u00e9quipe Une a su adapter son [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2864,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[82,2],"tags":[],"class_list":["post-2867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archives","category-seniors"],"_links":{"self":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/2867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/comments?post=2867"}],"version-history":[{"count":0,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/2867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/media\/2864"}],"wp:attachment":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/media?parent=2867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/categories?post=2867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/tags?post=2867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}