{"id":2842,"date":"2019-01-13T22:11:41","date_gmt":"2019-01-13T21:11:41","guid":{"rendered":"https:\/\/archives.courbevoie-rugby.com\/index.php\/2019\/01\/13\/resultats-du-1er-week-end-de-2019-3\/"},"modified":"2024-10-01T18:21:23","modified_gmt":"2024-10-01T16:21:23","slug":"resultats-du-1er-week-end-de-2019-3","status":"publish","type":"post","link":"https:\/\/archives.courbevoie-rugby.com\/index.php\/resultats-du-1er-week-end-de-2019-3\/","title":{"rendered":"R\u00e9sultats du 1er week-end de 2019"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\" size-full wp-image-2836\" src=\"https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/GA-3295.jpg\" alt=\"GA-3295.jpg\" width=\"80%\" height=\"NaN\" style=\"display: block; margin-left: auto; margin-right: auto;\" srcset=\"https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/GA-3295.jpg 1200w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/GA-3295-300x200.jpg 300w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/GA-3295-1024x683.jpg 1024w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/GA-3295-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p style=\"text-align: center;\"><em>L&rsquo;\u00e9quipe III face au XV des P\u00e9chus<\/em><\/p>\n<p>D\u00e9part en fanfare pour ce premier week-end de matchs de l&rsquo;ann\u00e9e 2019.<\/p>\n<p>&nbsp;<\/p>\n<p>Vendredi soir les Vieilles Branches ont pu rapidement se remettrent dans le bain en allant jouer \u00e0 Gargenville. Une \u00e9quipe inconnue pour nos VB qui ont du conc\u00e9der le match nul (3 essais de chaque c\u00f4t\u00e9) lors de la, longue, derni\u00e8re action. Match nul logique car si Gargenville a confisqu\u00e9 le ballon, les 3\/4 des VB ont su se montrer efficaces avec les quelques ballons qu&rsquo;ils ont eu.<\/p>\n<p>Samedi matin, l&rsquo;\u00e9quipe 3 , qui \u00e9volue en championnat FFSE, s&rsquo;est logiquement impos\u00e9e face au XV des P\u00e9chus 31 \u00e0 10 . L&rsquo;\u00e9quipe 3 seniors regroupe \u00e0 la fois d&rsquo;anciens juniors orphelins de la cat\u00e9gorie Belascain et de moins jeunes qui be veulent pas encore raccrocher les crampons, un bon melting-pot qui fonctionne bien depuis le d\u00e9but de saison !<\/p>\n<p>Samedi apr\u00e8s-midi, les deux \u00e9quipes U16 \u00e9taient en d\u00e9placement. L&rsquo;\u00e9quipe 1 (National) s&rsquo;impose avec un score \u00e0 l&rsquo;ancienne 8-7 \u00e0 Poissy face \u00e0 MLSP78. L&rsquo;\u00e9quipe 2 (Regional2) s&rsquo;incline \u00e0 Antony face \u00e0&#8230; Neuilly (leader de la poule) sur le score de 34 \u00e0 17. En soit ce r\u00e9sultat n&rsquo;a rien d&rsquo;extraordinaire, mais quand on songe qu&rsquo;au match aller Courbevoie avait perdu 105 \u00e0 5, c&rsquo;est comme une petite victoire pour cette \u00e9quipe qui a bien progress\u00e9 depuis le d\u00e9but de saison.<\/p>\n<p>Dimanche matin, les juniors s&rsquo;imposent au Massif :&nbsp;<a href=\"https:\/\/archives.courbevoie-rugby.com\/index.php\/2019\/01\/13\/u18-un-rcc-massif\/\">U18 : Un RCC massif <\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Dimanche apr\u00e8s-midi les deux \u00e9quipes seniors s&rsquo;imposent \u00e0 Rueil, 57-0 pour la B, 22-0 pour l&rsquo;\u00e9quipe Une<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; L&rsquo;\u00e9quipe III face au XV des P\u00e9chus D\u00e9part en fanfare pour ce premier week-end de matchs de l&rsquo;ann\u00e9e 2019. &nbsp; Vendredi soir les Vieilles Branches ont pu rapidement se remettrent dans le bain en allant jouer \u00e0 Gargenville. Une \u00e9quipe inconnue pour nos VB qui ont du conc\u00e9der le match nul (3 essais de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2836,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[82,32],"tags":[],"class_list":["post-2842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archives","category-equipes"],"_links":{"self":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/2842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/comments?post=2842"}],"version-history":[{"count":0,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/2842\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/media\/2836"}],"wp:attachment":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/media?parent=2842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/categories?post=2842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/tags?post=2842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}