{"id":2832,"date":"2019-01-07T11:30:10","date_gmt":"2019-01-07T10:30:10","guid":{"rendered":"https:\/\/archives.courbevoie-rugby.com\/index.php\/2019\/01\/07\/voeux-2019-du-president-du-rcc\/"},"modified":"2024-10-01T18:21:23","modified_gmt":"2024-10-01T16:21:23","slug":"voeux-2019-du-president-du-rcc","status":"publish","type":"post","link":"https:\/\/archives.courbevoie-rugby.com\/index.php\/voeux-2019-du-president-du-rcc\/","title":{"rendered":"Voeux 2019 du pr\u00e9sident du RCC"},"content":{"rendered":"<p>Courbevoie, le 1er Janvier 2019<\/p>\n<p>Madame, Monsieur, l\u00e9vriers et petits l\u00e9vriers,<\/p>\n<p>&nbsp;<\/p>\n<p>En ce d\u00e9but d\u2019ann\u00e9e 2019, je vous adresse, avec beaucoup d\u2019enthousiasme, \u00e0 vous et \u00e0 vos proches, mes v\u0153ux les plus sinc\u00e8res.<\/p>\n<p>Les saisons s\u2019encha\u00eenent et avec elles leurs lots de satisfactions. Le Club se porte de mieux en mieux et de nombreux projets fleurissent et viennent illustrer l\u2019\u00e9tat d\u2019esprit que vos enfants et vous portez. <br \/>Si je devais citer quelques \u00e9v\u00e8nements marquants de ce d\u00e9but de saison : <br \/>\u2022 Un gros succ\u00e8s aux inscriptions de Vitaville avec un effectif club maintenu \u00e0 plus de 650 licenci\u00e9s. <br \/>\u2022 Un carton plein encore pour Soustons ! Plus de 100 petits l\u00e9vriers hors de leur cynodrome. <br \/>\u2022 Une qualification en championnat national pour nos U16 et U18. <br \/>\u2022 Un tr\u00e8s bon d\u00e9but de saison pour nos s\u00e9niors, toujours invaincus. <br \/>\u2022 La cr\u00e9ation d\u2019une \u00e9quipe espoir pour donner du temps de jeu \u00e0 nos jeunes s\u00e9niors. <br \/>\u2022 La mise en place du sport sant\u00e9 pour les parents le samedi matin avec plus de 25 participants. <br \/>\u2022 Une AG financi\u00e8re fin d\u00e9cembre 2018 qui confirme le redressement du club et sa tr\u00e8s bonne sant\u00e9 financi\u00e8re, comme nous nous y \u00e9tions engag\u00e9s.<\/p>\n<p>Je pourrais bien \u00e9videmment poursuivre cette liste qui prouve que ce club a quelque chose d\u2019unique mais j\u2019aime aussi profiter de cet \u00e9dito pour aborder des sujets qui d\u00e9passent notre seul club. <br \/>Je ne peux donc pas vous \u00e9crire en ce d\u00e9but d\u2019ann\u00e9e en \u00e9ludant le sujet important du moment qui concerne notre beau sport. L\u2019ann\u00e9e 2018 a vu la mort dramatique de deux jeunes rugbymen professionnels, l\u2019un d\u2019un malaise cardiaque, le deuxi\u00e8me d\u2019une rupture des cervicales. <br \/>Ces drames nous renvoient \u00e0 l\u2019absence pr\u00e9gnante de l\u2019un de nos l\u00e9vriers, Lo\u00efc Penvern, qui nous a quitt\u00e9s le 23 janvier 2013 d\u2019un malaise cardiaque apr\u00e8s un entra\u00eenement. Il aurait eu 21 ans. <br \/>Ce drame nous a alert\u00e9s sur le fait que les choses devaient \u00eatre am\u00e9lior\u00e9es et nous avons privil\u00e9gi\u00e9 la pr\u00e9vention. Les dirigeants, les \u00e9ducateurs sont form\u00e9s aux gestes de premier secours, des d\u00e9fibrillateurs sont en place dans les stades. Vous trouverez d\u2019ailleurs \u00e0 la fin de cet \u00e9dito les 10 r\u00e8gles d\u2019or du sportif \u00e9dit\u00e9es par l\u2019Association 14 pour la pr\u00e9vention du malaise cardiaque, avec Lo\u00efc en arri\u00e8re-plan. En ce qui concerne les commotions c\u00e9r\u00e9brales, nous avons lanc\u00e9 cette ann\u00e9e \u00ab protocom \u00bb pour sensibiliser dirigeants et \u00e9ducateurs \u00e0 leur d\u00e9tection et leur prise en charge. <br \/>Mais ne comptez pas sur moi pour d\u00e9nigrer ou r\u00e9inventer ce sport, comme d\u2019aucuns sont tent\u00e9s de le faire. Pour le pratiquer depuis de nombreuses ann\u00e9es, je continue de croire profond\u00e9ment en notre sport et en ses valeurs. Certes, nous pratiquons un sport \u00e0 risque mais il convient de remettre les choses en perspective. Ne confondons pas rugby amateur et rugby professionnel.<br \/>Dans notre club amateur, les engagements, les r\u00e8gles sont diff\u00e9rents et nous avons toujours privil\u00e9gi\u00e9 dans notre formation le rugby de mouvement plut\u00f4t que celui d\u2019affrontement.<br \/>Une \u00e9tude men\u00e9e en 2010 par l\u2019Institut de veille sanitaire recensait 246 d\u00e9c\u00e8s d&rsquo;origine traumatique lors d&rsquo;une activit\u00e9 sportive. Avec 149 d\u00e9c\u00e8s sur 246, les sports de montagne et aquatiques arrivent en t\u00eate de ce triste palmar\u00e8s. Cette ann\u00e9e-l\u00e0, il y eut 1 mort li\u00e9 au rugby, loin derri\u00e8re le v\u00e9lo, la randonn\u00e9e, le ski, le kayak et l\u2019\u00e9quitation. <br \/>Bien que le rugby ne soit pas le sport le plus \u00e0 risque, l\u2019accident peut arriver. Dans ce contexte, nous travaillons tous les jours avec une seule pr\u00e9occupation en t\u00eate : celle de permettre \u00e0 votre enfant de pratiquer sa passion en toute s\u00e9curit\u00e9. <br \/>Donc, soyons fiers de ce que nous vivons, de ce que nos enfants vivent \u00e0 travers le rugby et ayons confiance en leur passion, en ce sport et en notre club. <br \/>A court terme, <br \/>\u2022 le Samedi 12 janvier \u00e0 17H aura lieu, au stade Jean Pierre Rives, notre f\u00eate annuelle de l\u2019Ecole de rugby. Je vous y attends nombreux pour continuer \u00e0 faire connaissance et \u00e9changer sur l\u2019actualit\u00e9 du club. <br \/>\u2022 Le Dimanche 20 Janvier, \u00e0 l\u2019occasion du match s\u00e9nior, nous comm\u00e9morerons le souvenir de Lo\u00efc.<\/p>\n<p>L\u2019accomplissement de nos projets est bien \u00e9videmment li\u00e9 \u00e0 l\u2019engagement et aux efforts de nos \u00e9ducateurs, dirigeants, b\u00e9n\u00e9voles et parents, que je remercie tous vivement ici au nom de tous les l\u00e9vriers et petits l\u00e9vriers.<\/p>\n<p>Bonne ann\u00e9e \u00e0 tous !<\/p>\n<p>Bertrand Nicol<br \/>Pr\u00e9sident du RC Courbevoie<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\" size-full wp-image-2831\" src=\"https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/14.jpg\" alt=\"14.jpg\" width=\"80%\" height=\"NaN\" style=\"display: block; margin-left: auto; margin-right: auto;\" srcset=\"https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/14.jpg 800w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/14-202x300.jpg 202w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/14-688x1024.jpg 688w, https:\/\/archives.courbevoie-rugby.com\/wp-content\/uploads\/2019\/01\/14-768x1143.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Courbevoie, le 1er Janvier 2019 Madame, Monsieur, l\u00e9vriers et petits l\u00e9vriers, &nbsp; En ce d\u00e9but d\u2019ann\u00e9e 2019, je vous adresse, avec beaucoup d\u2019enthousiasme, \u00e0 vous et \u00e0 vos proches, mes v\u0153ux les plus sinc\u00e8res. Les saisons s\u2019encha\u00eenent et avec elles leurs lots de satisfactions. Le Club se porte de mieux en mieux et de nombreux [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2831,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[82,14],"tags":[],"class_list":["post-2832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archives","category-vie-du-club"],"_links":{"self":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/2832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/comments?post=2832"}],"version-history":[{"count":0,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/2832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/media\/2831"}],"wp:attachment":[{"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/media?parent=2832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/categories?post=2832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.courbevoie-rugby.com\/index.php\/wp-json\/wp\/v2\/tags?post=2832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}